{"id":282,"date":"2022-03-30T15:35:09","date_gmt":"2022-03-30T21:35:09","guid":{"rendered":"https:\/\/www.familyandkidsdentalpueblo.com\/?page_id=282"},"modified":"2024-05-13T13:13:39","modified_gmt":"2024-05-13T19:13:39","slug":"tratamientos-nerviosos-pediatricos","status":"publish","type":"page","link":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/","title":{"rendered":"Tratamientos nerviosos pedi\u00e1tricos"},"content":{"rendered":"<h2>Tratamientos nerviosos pedi\u00e1tricos en Pueblo, CO<\/h2>\n<p>\u00bfTu hijo tiene un dolor dental que no desaparece? \u00bfHas notado decoloraci\u00f3n en uno de sus dientes? Nuestros <a href=\"\/es\/servicios\/dentista-general-para-ninos\/\">dentistas<\/a> ofrecen dos tratamientos endod\u00f3nticos espec\u00edficos para salvar un diente afectado por da\u00f1os internos: la pulpectom\u00eda y la pulpotom\u00eda.<\/p>\n<h2>\u00bfQu\u00e9 hay dentro de los dientes de mi hijo?<\/h2>\n<p>La \u00fanica parte visible de nuestros dientes, sin rayos X, se llama corona. Vemos el esmalte blanco nacarado que recubre los dientes por encima de la l\u00ednea de las enc\u00edas. Sin embargo, al igual que un iceberg, nuestros dientes tienen muchas partes que no son visibles a simple vista.<\/p>\n<p>En el n\u00facleo de cada diente de la boca de tu hijo vive un nervio y un tejido conectivo conocido como pulpa. Cuando una caries, una grieta, una infecci\u00f3n dental interna o un traumatismo da\u00f1an un nervio dental, el diente doler\u00e1 y puede experimentar otros s\u00edntomas.<\/p>\n<p>Como padre, si notas alguna anomal\u00eda en los dientes o enc\u00edas de tu hijo, ll\u00e1manos para concertar una cita. \u00a1Si se diagnostica, vamos a aliviar el dolor de tu hijo y restaurar la buena salud oral con tratamientos nerviosos pedi\u00e1tricos, por lo que tu hijo tendr\u00e1 una raz\u00f3n para sonre\u00edr de nuevo!<\/p>\n<h2>S\u00edntomas de lesiones nerviosas dentales en ni\u00f1os<\/h2>\n<p>El primer s\u00edntoma de da\u00f1o del nervio dental es a menudo el dolor, pero un paciente puede tener da\u00f1o del nervio sin ning\u00fan s\u00edntoma. Los siguientes s\u00edntomas podr\u00edan indicar que tu hijo necesita visitar a nuestra consulta.<\/p>\n<ul>\n<li><strong>Dolor dental: <\/strong>Tanto el dolor persistente como el dolor intermitente podr\u00edan indicar da\u00f1os en el nervio de un diente. En algunos casos, el dolor empeora al masticar alimentos, al aplicar cualquier presi\u00f3n sobre el diente afectado o cuando alimentos calientes\/fr\u00edos entran en contacto con el diente.<\/li>\n<li><strong>Dolor al presionar: <\/strong>al morder con el diente afectado, tu hijo puede experimentar un dolor agudo.<\/li>\n<li><strong>Sensibilidad dental:<\/strong> Adem\u00e1s de la sensibilidad a la temperatura, el diente de tu hijo puede doler cuando come o bebe alimentos \u00e1cidos (alimentos o bebidas de naranja, lim\u00f3n, lima) o dulces. Com\u00fanmente, el dolor dental continuar\u00e1 durante un tiempo despu\u00e9s de comer o beber c\u00edtricos o dulces.<\/li>\n<li><strong>Sensibilidad e inflamaci\u00f3n de las enc\u00edas: <\/strong>Alrededor del diente da\u00f1ado, el tejido de las enc\u00edas de tu hijo puede hincharse, enrojecerse y ser sensible al tacto. La mayor\u00eda de las veces esto ocurre cuando un diente desarrolla una infecci\u00f3n o inflamaci\u00f3n pulpar.<\/li>\n<li><strong>Recesi\u00f3n de las enc\u00edas:<\/strong> Cuando las enc\u00edas se separan de un diente en respuesta a un da\u00f1o del nervio dental, el diente se vuelve m\u00e1s sensible. Las ra\u00edces de nuestros dientes no tienen esmalte protector. La exposici\u00f3n de las ra\u00edces de los dientes provoca un aumento del dolor.<\/li>\n<li><strong>Cambio de color: <\/strong>Un nervio dental da\u00f1ado puede causar la decoloraci\u00f3n del diente. Notar\u00e1s que el diente se oscurece a medida que el nervio muere y la pulpa se rompe.<\/li>\n<li><strong>Absceso: <\/strong>Si un diente sufre un da\u00f1o importante en el nervio o \u00e9ste se deja sin tratar, puede acumularse una bolsa de pus en la ra\u00edz del diente, dentro de la mand\u00edbula. Los s\u00edntomas de un absceso incluyen dolor agudo, inflamaci\u00f3n del tejido gingival y, en algunos casos, fiebre.<\/li>\n<\/ul>\n<p>Para que podamos preservar la cantidad \u00f3ptima de estructura dental natural durante los tratamientos del nervio dental, trae a tu hijo a la primera se\u00f1al de s\u00edntomas.<\/p>\n<blockquote>\n<h5><em> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3764\" src=\"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/08\/lightbulb.png\" alt=\"\" width=\"35\" height=\"35\" \/>\u00bfSAB\u00cdAS QU\u00c9? <\/em><\/h5>\n<p> Si un diente sufre una infecci\u00f3n, es importante tratarlo inmediatamente para evitar que la infecci\u00f3n se extienda m\u00e1s.<\/em><\/p><\/blockquote>\n<h2>C\u00f3mo diagnosticamos los da\u00f1os en los nervios dentales<\/h2>\n<p>En la cita de tu hijo, el dentista evaluar\u00e1 sus dientes y enc\u00edas para detectar signos de caries, infecci\u00f3n, inflamaci\u00f3n, decoloraci\u00f3n y recesi\u00f3n o inflamaci\u00f3n de las enc\u00edas. Dado que no podemos ver un nervio dental a simple vista, el diagn\u00f3stico de los problemas de la pulpa dental depende en gran medida de las radiograf\u00edas.<\/p>\n<h2>Acerca de los tratamientos de los nervios dentales<\/h2>\n<p>A menudo tratamos los problemas de los nervios dentales en los dientes primarios y permanentes, ya sea con una pulpotom\u00eda o pulpectom\u00eda. Ten la seguridad de que vamos a mantener a tu hijo c\u00f3modo durante los tratamientos de los nervios dentales. Nuestros objetivos principales son (1) detener el dolor, (2) restaurar la buena salud oral, y (3) restaurar la funci\u00f3n oral c\u00f3moda.<\/p>\n<ul>\n<li>Con la <strong>pulpotom\u00eda,<\/strong>extraemos la pulpa de un diente dentro de la corona pero no dentro de la ra\u00edz. Utilizamos este tratamiento del nervio dental con mayor frecuencia para los dientes de leche que han desarrollado caries profundas o que han sufrido un traumatismo. Este enfoque permite que el diente de leche permanezca en su lugar, preservando el espacio para el diente permanente, hasta que se caiga de forma natural.<\/li>\n<li>Una <strong>pulpectom\u00eda<\/strong> es la primera parte del tratamiento de conducto, pero no es necesaria una corona. Para una pulpectom\u00eda, el dentista de tus hijos eliminar\u00e1 toda la pulpa del diente afectado e insertar\u00e1 una sustancia artificial en su lugar. Esto permite que el diente permanezca intacto y \u00fatil, aunque el nervio del diente y el suministro de sangre ya no est\u00e1n presentes.<\/li>\n<\/ul>\n<h2>Trata el dolor dental en Pueblo hoy mismo<\/h2>\n<p>\u00bfSe ha quejado tu hijo de dolor dental? \u00bfHas notado decoloraci\u00f3n en alguno de los dientes de tu hijo? \u00bfHa sufrido tu hijo alg\u00fan traumatismo que haya podido da\u00f1ar sus dientes? El mejor curso de acci\u00f3n para un padre es llevar a tu hijo a una cita con uno de nuestros dentistas confiable y amable con los ni\u00f1os.<\/p>\n<p><a href=\"\/es\/contacto\/\">contacto con nosotros<\/a> Kids Dental hoy si tu hijo se queja de un dolor dental o si han sido diagnosticados con da\u00f1o en los nervios que pueden requerir tratamientos del nervio dental.<\/p>","protected":false},"excerpt":{"rendered":"<p>En la visita dental de tu hijo, nuestro dentista realizar\u00e1 una evaluaci\u00f3n dental completa, incluyendo radiograf\u00edas, si sospechamos que hay da\u00f1os en el nervio dental. Con los tratamientos de los nervios dentales pedi\u00e1tricos, los dientes con la pulpa da\u00f1ada pueden permanecer intactos.<\/p>","protected":false},"author":2,"featured_media":3432,"parent":3299,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-282","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Toothache? Discolored tooth? If necessary, we will relieve your child\u2019s pain and restore good oral health with pediatric nerve treatments.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Kids Dental | Our dental office is devoted to serving our community and ensuring everyone has affordable access to dental care. We have several payment options available in addition to dental insurance, including Medicaid and CareCredit.\" \/>\n\t\t<meta property=\"og:type\" content=\"company\" \/>\n\t\t<meta property=\"og:title\" content=\"Pediatric Nerve Treatments in [digcity] | Kids Dental\" \/>\n\t\t<meta property=\"og:description\" content=\"Toothache? Discolored tooth? If necessary, we will relieve your child\u2019s pain and restore good oral health with pediatric nerve treatments.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/04\/ToddlerSmilingOutside.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/04\/ToddlerSmilingOutside.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pediatric Nerve Treatments in [digcity] | Kids Dental\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Toothache? Discolored tooth? If necessary, we will relieve your child\u2019s pain and restore good oral health with pediatric nerve treatments.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/08\/Pueblo-logo-3.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/#listItem\",\"name\":\"Services\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/#listItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/#listItem\",\"name\":\"General Dentist for Children\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/#listItem\",\"position\":3,\"name\":\"General Dentist for Children\",\"item\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#listItem\",\"name\":\"Pediatric Nerve Treatments\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/#listItem\",\"name\":\"Services\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#listItem\",\"position\":4,\"name\":\"Pediatric Nerve Treatments\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/#listItem\",\"name\":\"General Dentist for Children\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/#organization\",\"name\":\"Kids Dental\",\"description\":\"Our dental office is devoted to serving our community and ensuring everyone has affordable access to dental care. We have several payment options available in addition to dental insurance, including Medicaid and CareCredit.\",\"url\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/\",\"email\":\"Info@familyandkidsdentalpueblo.com\",\"telephone\":\"+17192048675\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pueblo-logo-3.webp\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#organizationLogo\",\"width\":579,\"height\":579},\"image\":{\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/familyandkidsdental\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/family-and-kids-dental-pueblo\"],\"address\":{\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"1022 Liberty Lane\",\"postalCode\":\"81001\",\"addressLocality\":\"Pueblo\",\"addressRegion\":\"Colorado\",\"addressCountry\":\"US\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#webpage\",\"url\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/\",\"name\":\"Pediatric Nerve Treatments in [digcity] | Kids Dental\",\"description\":\"Toothache? Discolored tooth? If necessary, we will relieve your child\\u2019s pain and restore good oral health with pediatric nerve treatments.\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ToddlerSmilingOutside.jpg\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#mainImage\",\"width\":600,\"height\":600,\"caption\":\"Young Girl Smiling Outdoors looking at the sky\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/services\\\/general-dentist-for-children\\\/pediatric-nerve-treatments\\\/#mainImage\"},\"datePublished\":\"2022-03-30T15:35:09-06:00\",\"dateModified\":\"2024-05-13T13:13:39-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/\",\"name\":\"Kids Dental\",\"alternateName\":\"Kids Dental\",\"description\":\"Our dental office is devoted to serving our community and ensuring everyone has affordable access to dental care. We have several payment options available in addition to dental insurance, including Medicaid and CareCredit.\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.familyandkidsdentalpueblo.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pediatric Nerve Treatments in [digcity] | Kids Dental<\/title>\n\n","aioseo_head_json":{"title":"Pediatric Nerve Treatments in [digcity] | Kids Dental","description":"\u00bfDolor dental? \u00bfDientes descoloridos? Si es necesario, vamos a aliviar el dolor de tu hijo y restaurar la buena salud oral con tratamientos nerviosos pedi\u00e1tricos.","canonical_url":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/www.familyandkidsdentalpueblo.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/#listItem","name":"Services"}},{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/#listItem","position":2,"name":"Services","item":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/#listItem","name":"General Dentist for Children"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/#listItem","position":3,"name":"General Dentist for Children","item":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#listItem","name":"Pediatric Nerve Treatments"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/#listItem","name":"Services"}},{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#listItem","position":4,"name":"Pediatric Nerve Treatments","previousItem":{"@type":"ListItem","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/#listItem","name":"General Dentist for Children"}}]},{"@type":"Organization","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/#organization","name":"Kids Dental","description":"Our dental office is devoted to serving our community and ensuring everyone has affordable access to dental care. We have several payment options available in addition to dental insurance, including Medicaid and CareCredit.","url":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/","email":"Info@familyandkidsdentalpueblo.com","telephone":"+17192048675","logo":{"@type":"ImageObject","url":"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/08\/Pueblo-logo-3.webp","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#organizationLogo","width":579,"height":579},"image":{"@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/familyandkidsdental\/","https:\/\/www.yelp.com\/biz\/family-and-kids-dental-pueblo"],"address":{"@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"1022 Liberty Lane","postalCode":"81001","addressLocality":"Pueblo","addressRegion":"Colorado","addressCountry":"US"}},{"@type":"WebPage","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#webpage","url":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/","name":"Pediatric Nerve Treatments in [digcity] | Kids Dental","description":"Toothache? Discolored tooth? If necessary, we will relieve your child\u2019s pain and restore good oral health with pediatric nerve treatments.","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/04\/ToddlerSmilingOutside.jpg","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#mainImage","width":600,"height":600,"caption":"Young Girl Smiling Outdoors looking at the sky"},"primaryImageOfPage":{"@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/#mainImage"},"datePublished":"2022-03-30T15:35:09-06:00","dateModified":"2024-05-13T13:13:39-06:00"},{"@type":"WebSite","@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/#website","url":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/","name":"Kids Dental","alternateName":"Kids Dental","description":"Our dental office is devoted to serving our community and ensuring everyone has affordable access to dental care. We have several payment options available in addition to dental insurance, including Medicaid and CareCredit.","inLanguage":"es-MX","publisher":{"@id":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Kids Dental | Our dental office is devoted to serving our community and ensuring everyone has affordable access to dental care. We have several payment options available in addition to dental insurance, including Medicaid and CareCredit.","og:type":"company","og:title":"Pediatric Nerve Treatments in [digcity] | Kids Dental","og:description":"Toothache? Discolored tooth? If necessary, we will relieve your child\u2019s pain and restore good oral health with pediatric nerve treatments.","og:url":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/","og:image":"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/04\/ToddlerSmilingOutside.jpg","og:image:secure_url":"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/04\/ToddlerSmilingOutside.jpg","og:image:width":600,"og:image:height":600,"twitter:card":"summary_large_image","twitter:title":"Pediatric Nerve Treatments in [digcity] | Kids Dental","twitter:description":"Toothache? Discolored tooth? If necessary, we will relieve your child\u2019s pain and restore good oral health with pediatric nerve treatments.","twitter:image":"https:\/\/www.familyandkidsdentalpueblo.com\/wp-content\/uploads\/2024\/08\/Pueblo-logo-3.webp"},"aioseo_meta_data":{"post_id":"282","title":"#post_title in [digcity] #separator_sa #site_title","description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"Root Canals","score":37,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63e5709c54586","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-13 20:25:29","limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2022-03-30 21:35:09","updated":"2026-05-13 20:25:29","breadcrumb_settings":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.familyandkidsdentalpueblo.com\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/\" title=\"Services\">Services<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/\" title=\"General Dentist for Children\">General Dentist for Children<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPediatric Nerve Treatments\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.familyandkidsdentalpueblo.com\/es"},{"label":"Services","link":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/"},{"label":"General Dentist for Children","link":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/"},{"label":"Pediatric Nerve Treatments","link":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/services\/general-dentist-for-children\/pediatric-nerve-treatments\/"}],"_links":{"self":[{"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/pages\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/pages\/282\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/pages\/3299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/media\/3432"}],"wp:attachment":[{"href":"https:\/\/www.familyandkidsdentalpueblo.com\/es\/wp-json\/wp\/v2\/media?parent=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}